{"id":2741,"date":"2024-03-15T12:20:02","date_gmt":"2024-03-15T11:20:02","guid":{"rendered":"http:\/\/evaas.vetagro-sup.fr\/?p=2741"},"modified":"2025-02-18T16:54:19","modified_gmt":"2025-02-18T15:54:19","slug":"participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils","status":"publish","type":"post","link":"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/","title":{"rendered":"Participation du p\u00f4le EVAAS au suivi long terme de chevreuils"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2741\" class=\"elementor elementor-2741\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68b342a elementor-section-boxed elementor-section-height-default elementor-section-height-default reptro-section-padding-large\" data-id=\"68b342a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c3a72d0\" data-id=\"c3a72d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9565d9 elementor-widget elementor-widget-text-editor\" data-id=\"f9565d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tout au long de cet hiver,<strong> le p\u00f4le EVAAS \u00e9tait un fois de plus sur le terrain aux c\u00f4t\u00e9s des \u00e9quipes de l\u2019OFB et du LBBE pour aider aux captures de chevreuils<\/strong>, dans le cadre du suivi longitudinal des populations de la R\u00e9serve Biologique Int\u00e9grale de Chiz\u00e9 (Deux-S\u00e8vres) et du Territoire d&rsquo;\u00c9tudes et d\u2019Exp\u00e9rimentations de Trois-Fontaines (Marne).<\/p><p><strong>Ce suivi, <\/strong>op\u00e9r\u00e9 depuis presque 50 ans maintenant, <strong>est l\u2019un des plus longs et plus complets au monde sur des populations de mammif\u00e8res sauvages<\/strong>. <strong>Il permet d\u2019\u00e9tudier pour cette esp\u00e8ce les dynamiques de populations, leur \u00e9co-\u00e9pid\u00e9miologie et leur \u00e9co-physiologie.<\/strong> Le suivi de ces deux populations, expos\u00e9es \u00e0 des conditions environnementales diff\u00e9rentes, permet \u00e9galement d\u2019\u00e9tudier le r\u00f4le de l&rsquo;environnement sur ces processus \u00e9volutifs et \u00e9pid\u00e9miologiques.<\/p><p>Le chevreuil est une esp\u00e8ce \u00ab ing\u00e9nieure des \u00e9cosyst\u00e8mes \u00bb abondante et particuli\u00e8rement chass\u00e9e en France (et plus globalement dans toute l\u2019Europe). <strong>Les travaux men\u00e9s autour de ces suivis apportent ainsi des connaissances pr\u00e9cieuses pour une gestion plus raisonn\u00e9e de l\u2019esp\u00e8ce et pour limiter les conflits avec les activit\u00e9s humaines<\/strong> (collisions routi\u00e8res, portage d\u2019agents pathog\u00e8nes, d\u00e9g\u00e2ts li\u00e9s \u00e0 la r\u00e9g\u00e9n\u00e9ration foresti\u00e8re, etc.).<\/p><p>Ce suivi est <strong>l\u2019occasion pour les membres du p\u00f4le EVAAS de participer \u00e0 la capture et \u00e0 la manipulation des animaux, ainsi que d\u2019aider aux diff\u00e9rents pr\u00e9l\u00e8vements biologiques et de r\u00e9aliser les soins v\u00e9t\u00e9rinaires<\/strong> n\u00e9cessaires.<\/p><p>Si ce sujet vous int\u00e9resse, n\u2019h\u00e9sitez pas \u00e0 consulter la page du LBBE consacr\u00e9e \u00e0 ce suivi\u00a0: <a href=\"https:\/\/lbbe.univ-lyon1.fr\/fr\/suivi-long-terme-chevreuils\">https:\/\/lbbe.univ-lyon1.fr\/fr\/suivi-long-terme-chevreuils<\/a><\/p><p>\u00a0<\/p><p>Cr\u00e9dits photos : Fran\u00e7ois D\u00e9bias (photo en t\u00eate d&rsquo;article) et Gilles Bourgoin (photo en bas d&rsquo;article)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d2a057 elementor-widget elementor-widget-image\" data-id=\"7d2a057\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"775\" src=\"http:\/\/evaas.vetagro-sup.fr\/wp-content\/uploads\/2024\/03\/IMG_9957-846x1024.jpeg\" class=\"attachment-large size-large wp-image-2745\" alt=\"\" srcset=\"http:\/\/evaas.vetagro-sup.fr\/wp-content\/uploads\/2024\/03\/IMG_9957-846x1024.jpeg 846w, http:\/\/evaas.vetagro-sup.fr\/wp-content\/uploads\/2024\/03\/IMG_9957-248x300.jpeg 248w, http:\/\/evaas.vetagro-sup.fr\/wp-content\/uploads\/2024\/03\/IMG_9957-768x929.jpeg 768w, http:\/\/evaas.vetagro-sup.fr\/wp-content\/uploads\/2024\/03\/IMG_9957-1269x1536.jpeg 1269w, http:\/\/evaas.vetagro-sup.fr\/wp-content\/uploads\/2024\/03\/IMG_9957.jpeg 1652w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Tout au long de cet hiver, le p\u00f4le EVAAS \u00e9tait un fois de plus sur le terrain aux c\u00f4t\u00e9s des \u00e9quipes de l\u2019OFB et du LBBE pour aider aux captures de chevreuils, dans le cadre du suivi longitudinal des populations de la R\u00e9serve Biologique Int\u00e9grale de Chiz\u00e9 (Deux-S\u00e8vres) et du Territoire d&rsquo;\u00c9tudes et d\u2019Exp\u00e9rimentations de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2744,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[4],"tags":[54,53,55],"class_list":["post-2741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expertise","tag-capture","tag-chevreuil-deurope","tag-programme-scientifique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Participation du p\u00f4le EVAAS au suivi long terme de chevreuils - EVAAS<\/title>\n<meta name=\"description\" content=\"Tout au long de cet hiver, le p\u00f4le EVAAS \u00e9tait un fois de plus sur le terrain aux c\u00f4t\u00e9s des \u00e9quipes de l\u2019OFB et du LBBE pour aider aux captures de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Participation du p\u00f4le EVAAS au suivi long terme de chevreuils - EVAAS\" \/>\n<meta property=\"og:description\" content=\"Tout au long de cet hiver, le p\u00f4le EVAAS \u00e9tait un fois de plus sur le terrain aux c\u00f4t\u00e9s des \u00e9quipes de l\u2019OFB et du LBBE pour aider aux captures de\" \/>\n<meta property=\"og:url\" content=\"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/\" \/>\n<meta property=\"og:site_name\" content=\"EVAAS\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-15T11:20:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-18T15:54:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/evaas.vetagro-sup.fr\/wp-content\/uploads\/2024\/03\/DSC_5544.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"evaas-admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"evaas-admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/index.php\\\/2024\\\/03\\\/15\\\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/index.php\\\/2024\\\/03\\\/15\\\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\\\/\"},\"author\":{\"name\":\"evaas-admin\",\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/#\\\/schema\\\/person\\\/39f69ac7780ac371f9ef27b9d4d91507\"},\"headline\":\"Participation du p\u00f4le EVAAS au suivi long terme de chevreuils\",\"datePublished\":\"2024-03-15T11:20:02+00:00\",\"dateModified\":\"2025-02-18T15:54:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/index.php\\\/2024\\\/03\\\/15\\\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\\\/\"},\"wordCount\":323,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/index.php\\\/2024\\\/03\\\/15\\\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/DSC_5544.png\",\"keywords\":[\"capture\",\"Chevreuil d'Europe\",\"programme scientifique\"],\"articleSection\":[\"Expertise\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/index.php\\\/2024\\\/03\\\/15\\\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/index.php\\\/2024\\\/03\\\/15\\\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\\\/\",\"url\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/index.php\\\/2024\\\/03\\\/15\\\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\\\/\",\"name\":\"Participation du p\u00f4le EVAAS au suivi long terme de chevreuils - EVAAS\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/index.php\\\/2024\\\/03\\\/15\\\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/index.php\\\/2024\\\/03\\\/15\\\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/DSC_5544.png\",\"datePublished\":\"2024-03-15T11:20:02+00:00\",\"dateModified\":\"2025-02-18T15:54:19+00:00\",\"description\":\"Tout au long de cet hiver, le p\u00f4le EVAAS \u00e9tait un fois de plus sur le terrain aux c\u00f4t\u00e9s des \u00e9quipes de l\u2019OFB et du LBBE pour aider aux captures de\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/index.php\\\/2024\\\/03\\\/15\\\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/index.php\\\/2024\\\/03\\\/15\\\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/index.php\\\/2024\\\/03\\\/15\\\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\\\/#primaryimage\",\"url\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/DSC_5544.png\",\"contentUrl\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/DSC_5544.png\",\"width\":1024,\"height\":682,\"caption\":\"Rel\u00e2ch\u00e9 d'un chevreuil dans le cadre d'un suivi de population\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/index.php\\\/2024\\\/03\\\/15\\\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Participation du p\u00f4le EVAAS au suivi long terme de chevreuils\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/#website\",\"url\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/\",\"name\":\"EVAAS\",\"description\":\"Expertise scientifique collective multidisciplinaire en sant\u00e9 de la faune sauvage\",\"publisher\":{\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/#organization\",\"name\":\"P\u00f4le EVAAS\",\"url\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo_EVAAS_ecran_sans_fond-e1539174118936.png\",\"contentUrl\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo_EVAAS_ecran_sans_fond-e1539174118936.png\",\"width\":387,\"height\":150,\"caption\":\"P\u00f4le EVAAS\"},\"image\":{\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/#\\\/schema\\\/person\\\/39f69ac7780ac371f9ef27b9d4d91507\",\"name\":\"evaas-admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be92b5b6d77942219df2ecf66ba3207feb2e7c5d543d0411293de093ed0c1dd3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be92b5b6d77942219df2ecf66ba3207feb2e7c5d543d0411293de093ed0c1dd3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be92b5b6d77942219df2ecf66ba3207feb2e7c5d543d0411293de093ed0c1dd3?s=96&d=mm&r=g\",\"caption\":\"evaas-admin\"},\"url\":\"http:\\\/\\\/evaas.vetagro-sup.fr\\\/index.php\\\/author\\\/evaas-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Participation du p\u00f4le EVAAS au suivi long terme de chevreuils - EVAAS","description":"Tout au long de cet hiver, le p\u00f4le EVAAS \u00e9tait un fois de plus sur le terrain aux c\u00f4t\u00e9s des \u00e9quipes de l\u2019OFB et du LBBE pour aider aux captures de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/","og_locale":"fr_FR","og_type":"article","og_title":"Participation du p\u00f4le EVAAS au suivi long terme de chevreuils - EVAAS","og_description":"Tout au long de cet hiver, le p\u00f4le EVAAS \u00e9tait un fois de plus sur le terrain aux c\u00f4t\u00e9s des \u00e9quipes de l\u2019OFB et du LBBE pour aider aux captures de","og_url":"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/","og_site_name":"EVAAS","article_published_time":"2024-03-15T11:20:02+00:00","article_modified_time":"2025-02-18T15:54:19+00:00","og_image":[{"width":1024,"height":682,"url":"http:\/\/evaas.vetagro-sup.fr\/wp-content\/uploads\/2024\/03\/DSC_5544.png","type":"image\/png"}],"author":"evaas-admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"evaas-admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/#article","isPartOf":{"@id":"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/"},"author":{"name":"evaas-admin","@id":"http:\/\/evaas.vetagro-sup.fr\/#\/schema\/person\/39f69ac7780ac371f9ef27b9d4d91507"},"headline":"Participation du p\u00f4le EVAAS au suivi long terme de chevreuils","datePublished":"2024-03-15T11:20:02+00:00","dateModified":"2025-02-18T15:54:19+00:00","mainEntityOfPage":{"@id":"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/"},"wordCount":323,"commentCount":0,"publisher":{"@id":"http:\/\/evaas.vetagro-sup.fr\/#organization"},"image":{"@id":"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/#primaryimage"},"thumbnailUrl":"http:\/\/evaas.vetagro-sup.fr\/wp-content\/uploads\/2024\/03\/DSC_5544.png","keywords":["capture","Chevreuil d'Europe","programme scientifique"],"articleSection":["Expertise"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/","url":"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/","name":"Participation du p\u00f4le EVAAS au suivi long terme de chevreuils - EVAAS","isPartOf":{"@id":"http:\/\/evaas.vetagro-sup.fr\/#website"},"primaryImageOfPage":{"@id":"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/#primaryimage"},"image":{"@id":"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/#primaryimage"},"thumbnailUrl":"http:\/\/evaas.vetagro-sup.fr\/wp-content\/uploads\/2024\/03\/DSC_5544.png","datePublished":"2024-03-15T11:20:02+00:00","dateModified":"2025-02-18T15:54:19+00:00","description":"Tout au long de cet hiver, le p\u00f4le EVAAS \u00e9tait un fois de plus sur le terrain aux c\u00f4t\u00e9s des \u00e9quipes de l\u2019OFB et du LBBE pour aider aux captures de","breadcrumb":{"@id":"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/#primaryimage","url":"http:\/\/evaas.vetagro-sup.fr\/wp-content\/uploads\/2024\/03\/DSC_5544.png","contentUrl":"http:\/\/evaas.vetagro-sup.fr\/wp-content\/uploads\/2024\/03\/DSC_5544.png","width":1024,"height":682,"caption":"Rel\u00e2ch\u00e9 d'un chevreuil dans le cadre d'un suivi de population"},{"@type":"BreadcrumbList","@id":"http:\/\/evaas.vetagro-sup.fr\/index.php\/2024\/03\/15\/participation-du-pole-evaas-au-suivi-long-terme-de-chevreuils\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/evaas.vetagro-sup.fr\/"},{"@type":"ListItem","position":2,"name":"Participation du p\u00f4le EVAAS au suivi long terme de chevreuils"}]},{"@type":"WebSite","@id":"http:\/\/evaas.vetagro-sup.fr\/#website","url":"http:\/\/evaas.vetagro-sup.fr\/","name":"EVAAS","description":"Expertise scientifique collective multidisciplinaire en sant\u00e9 de la faune sauvage","publisher":{"@id":"http:\/\/evaas.vetagro-sup.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/evaas.vetagro-sup.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"http:\/\/evaas.vetagro-sup.fr\/#organization","name":"P\u00f4le EVAAS","url":"http:\/\/evaas.vetagro-sup.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/evaas.vetagro-sup.fr\/#\/schema\/logo\/image\/","url":"http:\/\/evaas.vetagro-sup.fr\/wp-content\/uploads\/2018\/10\/logo_EVAAS_ecran_sans_fond-e1539174118936.png","contentUrl":"http:\/\/evaas.vetagro-sup.fr\/wp-content\/uploads\/2018\/10\/logo_EVAAS_ecran_sans_fond-e1539174118936.png","width":387,"height":150,"caption":"P\u00f4le EVAAS"},"image":{"@id":"http:\/\/evaas.vetagro-sup.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/evaas.vetagro-sup.fr\/#\/schema\/person\/39f69ac7780ac371f9ef27b9d4d91507","name":"evaas-admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/be92b5b6d77942219df2ecf66ba3207feb2e7c5d543d0411293de093ed0c1dd3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/be92b5b6d77942219df2ecf66ba3207feb2e7c5d543d0411293de093ed0c1dd3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be92b5b6d77942219df2ecf66ba3207feb2e7c5d543d0411293de093ed0c1dd3?s=96&d=mm&r=g","caption":"evaas-admin"},"url":"http:\/\/evaas.vetagro-sup.fr\/index.php\/author\/evaas-admin\/"}]}},"_links":{"self":[{"href":"http:\/\/evaas.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/posts\/2741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/evaas.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/evaas.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/evaas.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/evaas.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2741"}],"version-history":[{"count":5,"href":"http:\/\/evaas.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/posts\/2741\/revisions"}],"predecessor-version":[{"id":2748,"href":"http:\/\/evaas.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/posts\/2741\/revisions\/2748"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/evaas.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/media\/2744"}],"wp:attachment":[{"href":"http:\/\/evaas.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/evaas.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2741"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/evaas.vetagro-sup.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}